{"id":21,"date":"2024-07-16T18:40:10","date_gmt":"2024-07-16T18:40:10","guid":{"rendered":"https:\/\/domain-selection.com\/?page_id=21"},"modified":"2025-10-19T16:27:55","modified_gmt":"2025-10-19T16:27:55","slug":"about-us","status":"publish","type":"page","link":"https:\/\/www.imko.de\/en\/ueber-uns\/","title":{"rendered":"About us"},"content":{"rendered":"<section class=\"section\" id=\"section_270256459\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1244201137\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1500\" height=\"430\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/banner-ueber-uns.jpg\" class=\"bg attachment-original size-original\" alt=\"banner-ueber-uns\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1833447388\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1833447388 {\n  width: 60%;\n}\n#text-box-1833447388 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1833447388 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1244201137 {\n  padding-top: 150px;\n  background-color: rgb(255,255,255);\n}\n#banner-1244201137 .banner-bg img {\n  object-position: 72% 61%;\n}\n@media (min-width:550px) {\n  #banner-1244201137 {\n    padding-top: 520px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_270256459 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1500497262\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-708471745\">\n\n\n\t<div id=\"col-1167463799\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h1>About us<\/h1>\n<p>Get to know the experts for precise moisture measurement.<br \/>We develop, produce and distribute state-of-the-art measurement technology and sensors.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1167463799 > .col-inner {\n  margin: 40px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1500497262 {\n  padding-top: 10px;\n  padding-bottom: 10px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_598819419\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-middle align-center\"  id=\"row-1752718397\">\n\n\n\t<div id=\"col-1671406408\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-22142947\" class=\"text\">\n\t\t\n\n\t\t\t<!-- Cool Timeline Free V3.3.1 -->\n\t\t\t<div class=\"ctl-wrapper\" role=\"region\" aria-label=\"Timeline\">\n\t\t\t\t<div class=\"ctl-before-content\"><div class=\"timeline-main-title\"><h2>Our company history<\/h2><\/div><\/div>\t\t\t\t<div id=\"cool_timeline_1\" class=\"cool-timeline-wrapper ctl-both-sided ctl-vertical-wrapper\" >\n\t\t\t\t\t<div class=\"ctl-start\"><\/div>\n\t\t\t\t\t<!-- Timeline Container -->\n\t\t\t\t\t<div class=\"ctl-timeline ctl-timeline-container\" data-animation=\"fade-up\">\n\t\t\t\t\t\t<!-- Center Line -->\n\t\t\t\t\t\t<div class=\"ctl-inner-line\" role=\"presentation\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<!-- Timeline Content --><div  id=\"ctl-story-295\" class=\"ctl-story ctl-story-dot-icon odd ctl-story-right\" data-aos=\"fade-up\"   data-story-index=\"1\" role=\"article\"><!-- Story Date --><div class=\"ctl-labels\"><div class=\"ctl-label-big story-date\">1984<\/div><\/div><!-- Story IconDot --><div class=\"ctl-icondot\"><\/div> <!-- Story Arrow --><div class=\"ctl-arrow\"><\/div><!-- Story Content --><div class=\"ctl-content\"><!-- Story Title --><div class=\"ctl-title story-295\" aria-label=\"2\">Foundation of IMKO Micromodultechnik GmbH<\/div><\/div><\/div><!-- Timeline Content --><div  id=\"ctl-story-294\" class=\"ctl-story ctl-story-dot-icon even ctl-story-left\" data-aos=\"fade-up\"   data-story-index=\"2\" role=\"article\"><!-- Story Date --><div class=\"ctl-labels\"><div class=\"ctl-label-big story-date\">1990<\/div><\/div><!-- Story IconDot --><div class=\"ctl-icondot\"><\/div> <!-- Story Arrow --><div class=\"ctl-arrow\"><\/div><!-- Story Content --><div class=\"ctl-content\"><!-- Story Title --><div class=\"ctl-title story-294\" aria-label=\"2\">Market launch of soil moisture products with TRIME TDR technology<\/div><\/div><\/div><!-- Timeline Content --><div  id=\"ctl-story-293\" class=\"ctl-story ctl-story-dot-icon odd ctl-story-right\" data-aos=\"fade-up\"   data-story-index=\"3\" role=\"article\"><!-- Story Date --><div class=\"ctl-labels\"><div class=\"ctl-label-big story-date\">1993<\/div><\/div><!-- Story IconDot --><div class=\"ctl-icondot\"><\/div> <!-- Story Arrow --><div class=\"ctl-arrow\"><\/div><!-- Story Content --><div class=\"ctl-content\"><!-- Story Title --><div class=\"ctl-title story-293\" aria-label=\"2\">Dr Rudolf Eberle Prize Innovation Award of the State of Baden-W\u00fcrttemberg for soil and material moisture measuring system<\/div><\/div><\/div><!-- Timeline Content --><div  id=\"ctl-story-292\" class=\"ctl-story ctl-story-dot-icon even ctl-story-left\" data-aos=\"fade-up\"   data-story-index=\"4\" role=\"article\"><!-- Story Date --><div class=\"ctl-labels\"><div class=\"ctl-label-big story-date\">1999<\/div><\/div><!-- Story IconDot --><div class=\"ctl-icondot\"><\/div> <!-- Story Arrow --><div class=\"ctl-arrow\"><\/div><!-- Story Content --><div class=\"ctl-content\"><!-- Story Title --><div class=\"ctl-title story-292\" aria-label=\"2\">Silver medal from the German Agricultural Society (DLG) for TRIME GW<\/div><\/div><\/div><!-- Timeline Content --><div  id=\"ctl-story-1550\" class=\"ctl-story ctl-story-dot-icon odd ctl-story-right\" data-aos=\"fade-up\"   data-story-index=\"5\" role=\"article\"><!-- Story Date --><div class=\"ctl-labels\"><div class=\"ctl-label-big story-date\">2001<\/div><\/div><!-- Story IconDot --><div class=\"ctl-icondot\"><\/div> <!-- Story Arrow --><div class=\"ctl-arrow\"><\/div><!-- Story Content --><div class=\"ctl-content\"><!-- Story Title --><div class=\"ctl-title story-1550\" aria-label=\"2\">Market launch of the GS1 surface probe<\/div><\/div><\/div><!-- Timeline Content --><div  id=\"ctl-story-1551\" class=\"ctl-story ctl-story-dot-icon even ctl-story-left\" data-aos=\"fade-up\"   data-story-index=\"6\" role=\"article\"><!-- Story Date --><div class=\"ctl-labels\"><div class=\"ctl-label-big story-date\">2006<\/div><\/div><!-- Story IconDot --><div class=\"ctl-icondot\"><\/div> <!-- Story Arrow --><div class=\"ctl-arrow\"><\/div><!-- Story Content --><div class=\"ctl-content\"><!-- Story Title --><div class=\"ctl-title story-1551\" aria-label=\"2\">Market launch of the TRIME PICO soil moisture series<\/div><\/div><\/div><!-- Timeline Content --><div  id=\"ctl-story-1552\" class=\"ctl-story ctl-story-dot-icon odd ctl-story-right\" data-aos=\"fade-up\"   data-story-index=\"7\" role=\"article\"><!-- Story Date --><div class=\"ctl-labels\"><div class=\"ctl-label-big story-date\">2009<\/div><\/div><!-- Story IconDot --><div class=\"ctl-icondot\"><\/div> <!-- Story Arrow --><div class=\"ctl-arrow\"><\/div><!-- Story Content --><div class=\"ctl-content\"><!-- Story Title --><div class=\"ctl-title story-1552\" aria-label=\"2\">Market launch of SONO surface probes<\/div><\/div><\/div><!-- Timeline Content --><div  id=\"ctl-story-1553\" class=\"ctl-story ctl-story-dot-icon even ctl-story-left\" data-aos=\"fade-up\"   data-story-index=\"8\" role=\"article\"><!-- Story Date --><div class=\"ctl-labels\"><div class=\"ctl-label-big story-date\">2016<\/div><\/div><!-- Story IconDot --><div class=\"ctl-icondot\"><\/div> <!-- Story Arrow --><div class=\"ctl-arrow\"><\/div><!-- Story Content --><div class=\"ctl-content\"><!-- Story Title --><div class=\"ctl-title story-1553\" aria-label=\"2\">bauma Innovation Award for the SONO WZ hand probe<\/div><\/div><\/div><!-- Timeline Content --><div  id=\"ctl-story-1554\" class=\"ctl-story ctl-story-dot-icon odd ctl-story-right\" data-aos=\"fade-up\"   data-story-index=\"9\" role=\"article\"><!-- Story Date --><div class=\"ctl-labels\"><div class=\"ctl-label-big story-date\">2017<\/div><\/div><!-- Story IconDot --><div class=\"ctl-icondot\"><\/div> <!-- Story Arrow --><div class=\"ctl-arrow\"><\/div><!-- Story Content --><div class=\"ctl-content\"><!-- Story Title --><div class=\"ctl-title story-1554\" aria-label=\"2\">IMKO becomes part of the Endress+Hauser Group<\/div><\/div><\/div><!-- Timeline Content --><div  id=\"ctl-story-1555\" class=\"ctl-story ctl-story-dot-icon even ctl-story-left\" data-aos=\"fade-up\"   data-story-index=\"10\" role=\"article\"><!-- Story Date --><div class=\"ctl-labels\"><div class=\"ctl-label-big story-date\">2018<\/div><\/div><!-- Story IconDot --><div class=\"ctl-icondot\"><\/div> <!-- Story Arrow --><div class=\"ctl-arrow\"><\/div><!-- Story Content --><div class=\"ctl-content\"><!-- Story Title --><div class=\"ctl-title story-1555\" aria-label=\"2\">Increased measuring accuracy thanks to the introduction of a new ASIC generation<\/div><\/div><\/div><!-- Timeline Content --><div  id=\"ctl-story-1556\" class=\"ctl-story ctl-story-dot-icon odd ctl-story-right\" data-aos=\"fade-up\"   data-story-index=\"11\" role=\"article\"><!-- Story Date --><div class=\"ctl-labels\"><div class=\"ctl-label-big story-date\">2021<\/div><\/div><!-- Story IconDot --><div class=\"ctl-icondot\"><\/div> <!-- Story Arrow --><div class=\"ctl-arrow\"><\/div><!-- Story Content --><div class=\"ctl-content\"><!-- Story Title --><div class=\"ctl-title story-1556\" aria-label=\"2\">Market launch of the SONO-Ex ATEX probes<\/div><\/div><\/div><!-- Timeline Content --><div  id=\"ctl-story-1557\" class=\"ctl-story ctl-story-dot-icon even ctl-story-left\" data-aos=\"fade-up\"   data-story-index=\"12\" role=\"article\"><!-- Story Date --><div class=\"ctl-labels\"><div class=\"ctl-label-big story-date\">2024<\/div><\/div><!-- Story IconDot --><div class=\"ctl-icondot\"><\/div> <!-- Story Arrow --><div class=\"ctl-arrow\"><\/div><!-- Story Content --><div class=\"ctl-content\"><!-- Story Title --><div class=\"ctl-title story-1557\" aria-label=\"2\">Launch of the new IMKO CONNECT app for mobile measuring probes<\/div><\/div><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"ctl-end\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\n<style>\n#text-22142947 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_598819419 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_2110605243\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1302272900\">\n\n\n\t<div id=\"col-1666810873\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2>Your contact persons<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2092435195\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-666567606\" >\n    <div class=\"slider slider-nav-simple slider-nav-large slider-nav-dark slider-nav-outside slider-style-focus slider-show-nav\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 6000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": false,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"row ma-col\"  id=\"row-2000404254\">\n\n\n\t<div id=\"col-1423254556\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1 dark\" style=\"background-color:#007caa;\" >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1519195160\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1000\" height=\"691\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/portrait-stefan-rolf.webp\" class=\"attachment-original size-original\" alt=\"Portrait Stefan Rolf\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/portrait-stefan-rolf.webp 1000w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/portrait-stefan-rolf-510x352.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/portrait-stefan-rolf-300x207.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/portrait-stefan-rolf-768x531.webp 768w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/portrait-stefan-rolf-18x12.webp 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1519195160 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h4>Stefan Rolf<\/h4>\n<p>CEO<\/p>\n<div class=\"social-icons follow-icons\" ><a href=\"mailto:info@imko.de\" data-label=\"E-mail\" target=\"_blank\" class=\"icon plain email tooltip\" title=\"Send us an email\" aria-label=\"Send us an email\" rel=\"nofollow noopener\" ><i class=\"icon-envelop\" ><\/i><\/a><a href=\"tel:+49 7243 5921-0\" data-label=\"Phone\" target=\"_blank\" class=\"icon plain phone tooltip\" title=\"Call us\" aria-label=\"Call us\" rel=\"nofollow noopener\" ><i class=\"icon-phone\" ><\/i><\/a><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1423254556 > .col-inner {\n  padding: 0px 0px 25px 0px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row ma-col\"  id=\"row-1975968016\">\n\n\n\t<div id=\"col-78410893\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1 dark\" style=\"background-color:#007caa;\" >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_203338481\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/timo-camek.webp\" class=\"attachment-original size-original\" alt=\"timo-camek\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/timo-camek.webp 1000w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/timo-camek-510x340.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/timo-camek-300x200.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/timo-camek-768x512.webp 768w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/timo-camek-18x12.webp 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_203338481 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h4>Timo Camek<\/h4>\n<p>Team Leader Service &amp; Application<\/p>\n<div class=\"social-icons follow-icons\" ><a href=\"mailto:service@imko.de\" data-label=\"E-mail\" target=\"_blank\" class=\"icon plain email tooltip\" title=\"Send us an email\" aria-label=\"Send us an email\" rel=\"nofollow noopener\" ><i class=\"icon-envelop\" ><\/i><\/a><a href=\"tel:+49 7243 5921-0\" data-label=\"Phone\" target=\"_blank\" class=\"icon plain phone tooltip\" title=\"Call us\" aria-label=\"Call us\" rel=\"nofollow noopener\" ><i class=\"icon-phone\" ><\/i><\/a><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-78410893 > .col-inner {\n  padding: 0px 0px 25px 0px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row ma-col\"  id=\"row-2017475692\">\n\n\n\t<div id=\"col-1674802660\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1 dark\" style=\"background-color:#007caa;\" >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1997692137\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/sven-pitzal.webp\" class=\"attachment-original size-original\" alt=\"Portrait Sven Pitzal\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/sven-pitzal.webp 1000w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/sven-pitzal-510x340.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/sven-pitzal-300x200.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/sven-pitzal-768x512.webp 768w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/sven-pitzal-18x12.webp 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1997692137 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h4>Sven Pitzal<\/h4>\n<p>Purchasing &amp; Incoming Goods<\/p>\n<div class=\"social-icons follow-icons\" ><a href=\"mailto:einkauf@imko.de\" data-label=\"E-mail\" target=\"_blank\" class=\"icon plain email tooltip\" title=\"Send us an email\" aria-label=\"Send us an email\" rel=\"nofollow noopener\" ><i class=\"icon-envelop\" ><\/i><\/a><a href=\"tel:+49 7243 5921-0\" data-label=\"Phone\" target=\"_blank\" class=\"icon plain phone tooltip\" title=\"Call us\" aria-label=\"Call us\" rel=\"nofollow noopener\" ><i class=\"icon-phone\" ><\/i><\/a><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1674802660 > .col-inner {\n  padding: 0px 0px 25px 0px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row ma-col\"  id=\"row-1334292049\">\n\n\n\t<div id=\"col-407936994\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1 dark\" style=\"background-color:#007caa;\" >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1934154429\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/cornelius-jantschke.webp\" class=\"attachment-original size-original\" alt=\"cornelius-jantschke\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/cornelius-jantschke.webp 1000w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/cornelius-jantschke-510x340.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/cornelius-jantschke-300x200.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/cornelius-jantschke-768x512.webp 768w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/cornelius-jantschke-18x12.webp 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1934154429 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h4>Dr Cornelius Jantschke<\/h4>\n<p>Head of Sales &amp; Marketing<\/p>\n<div class=\"social-icons follow-icons\" ><a href=\"mailto:sales@imko.de\" data-label=\"E-mail\" target=\"_blank\" class=\"icon plain email tooltip\" title=\"Send us an email\" aria-label=\"Send us an email\" rel=\"nofollow noopener\" ><i class=\"icon-envelop\" ><\/i><\/a><a href=\"tel:+49 7243 5921-0\" data-label=\"Phone\" target=\"_blank\" class=\"icon plain phone tooltip\" title=\"Call us\" aria-label=\"Call us\" rel=\"nofollow noopener\" ><i class=\"icon-phone\" ><\/i><\/a><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-407936994 > .col-inner {\n  padding: 0px 0px 25px 0px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row ma-col\"  id=\"row-242556352\">\n\n\n\t<div id=\"col-1708414221\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1 dark\" style=\"background-color:#007caa;\" >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_726025204\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/dario-meringolo.webp\" class=\"attachment-original size-original\" alt=\"Portrait Dario Meringolo\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/dario-meringolo.webp 1000w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/dario-meringolo-510x340.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/dario-meringolo-300x200.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/dario-meringolo-768x512.webp 768w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/dario-meringolo-18x12.webp 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_726025204 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h4>Dario Meringolo<\/h4>\n<p>Order processing &amp; export<\/p>\n<div class=\"social-icons follow-icons\" ><a href=\"mailto:sales@imko.de\" data-label=\"E-mail\" target=\"_blank\" class=\"icon plain email tooltip\" title=\"Send us an email\" aria-label=\"Send us an email\" rel=\"nofollow noopener\" ><i class=\"icon-envelop\" ><\/i><\/a><a href=\"tel:+49 7243 5921-0\" data-label=\"Phone\" target=\"_blank\" class=\"icon plain phone tooltip\" title=\"Call us\" aria-label=\"Call us\" rel=\"nofollow noopener\" ><i class=\"icon-phone\" ><\/i><\/a><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1708414221 > .col-inner {\n  padding: 0px 0px 25px 0px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row ma-col\"  id=\"row-2131927434\">\n\n\n\t<div id=\"col-1562069573\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1 dark\" style=\"background-color:#007caa;\" >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_605877304\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/silke-vogel.webp\" class=\"attachment-original size-original\" alt=\"Portrait Silke Vogel\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/silke-vogel.webp 1000w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/silke-vogel-510x340.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/silke-vogel-300x200.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/silke-vogel-768x512.webp 768w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/silke-vogel-18x12.webp 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_605877304 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h4>Silke Vogel<\/h4>\n<p>Receiving Operator<\/p>\n<div class=\"social-icons follow-icons\" ><a href=\"mailto:einkauf@imko.de\" data-label=\"E-mail\" target=\"_blank\" class=\"icon plain email tooltip\" title=\"Send us an email\" aria-label=\"Send us an email\" rel=\"nofollow noopener\" ><i class=\"icon-envelop\" ><\/i><\/a><a href=\"tel:+49 7243 5921-0\" data-label=\"Phone\" target=\"_blank\" class=\"icon plain phone tooltip\" title=\"Call us\" aria-label=\"Call us\" rel=\"nofollow noopener\" ><i class=\"icon-phone\" ><\/i><\/a><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1562069573 > .col-inner {\n  padding: 0px 0px 25px 0px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row ma-col\"  id=\"row-582559615\">\n\n\n\t<div id=\"col-37757945\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1 dark\" style=\"background-color:#007caa;\" >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_114196282\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:180px;\">\n\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1708\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/franco-stano_portrait-scaled.webp\" class=\"attachment-original size-original\" alt=\"Franco Stano Potraitbild\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/franco-stano_portrait-scaled.webp 2560w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/franco-stano_portrait-300x200.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/franco-stano_portrait-1024x683.webp 1024w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/franco-stano_portrait-768x512.webp 768w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/franco-stano_portrait-1536x1025.webp 1536w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/franco-stano_portrait-2048x1366.webp 2048w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/franco-stano_portrait-18x12.webp 18w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/franco-stano_portrait-510x340.webp 510w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_114196282 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h4>Franco Stano<\/h4>\n<p>Repair &amp; Service<\/p>\n<div class=\"social-icons follow-icons\" ><a href=\"mailto:service@imko.de\" data-label=\"E-mail\" target=\"_blank\" class=\"icon plain email tooltip\" title=\"Send us an email\" aria-label=\"Send us an email\" rel=\"nofollow noopener\" ><i class=\"icon-envelop\" ><\/i><\/a><a href=\"tel:+49 7243 5921-0\" data-label=\"Phone\" target=\"_blank\" class=\"icon plain phone tooltip\" title=\"Call us\" aria-label=\"Call us\" rel=\"nofollow noopener\" ><i class=\"icon-phone\" ><\/i><\/a><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-37757945 > .col-inner {\n  padding: 0px 0px 25px 0px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row ma-col\"  id=\"row-13752128\">\n\n\n\t<div id=\"col-659133390\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1 dark\" style=\"background-color:#007caa;\" >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_581636985\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:180px;\">\n\t\t\t<img decoding=\"async\" width=\"8192\" height=\"5464\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/jan-zepp_portrait.webp\" class=\"attachment-original size-original\" alt=\"Jan Zepp Potraitbild\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/jan-zepp_portrait.webp 8192w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/jan-zepp_portrait-300x200.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/jan-zepp_portrait-1024x683.webp 1024w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/jan-zepp_portrait-768x512.webp 768w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/jan-zepp_portrait-1536x1025.webp 1536w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/jan-zepp_portrait-18x12.webp 18w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/jan-zepp_portrait-510x340.webp 510w\" sizes=\"(max-width: 8192px) 100vw, 8192px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_581636985 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p><strong>Jan Zepp<\/strong><\/p>\n<p>Technical sales<\/p>\n<div class=\"social-icons follow-icons\" ><a href=\"mailto:sales@imko.de\" data-label=\"E-mail\" target=\"_blank\" class=\"icon plain email tooltip\" title=\"Send us an email\" aria-label=\"Send us an email\" rel=\"nofollow noopener\" ><i class=\"icon-envelop\" ><\/i><\/a><a href=\"tel:+49 7243 5921-0\" data-label=\"Phone\" target=\"_blank\" class=\"icon plain phone tooltip\" title=\"Call us\" aria-label=\"Call us\" rel=\"nofollow noopener\" ><i class=\"icon-phone\" ><\/i><\/a><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-659133390 > .col-inner {\n  padding: 0px 0px 25px 0px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row ma-col\"  id=\"row-1666050122\">\n\n\n\t<div id=\"col-462807687\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1 dark\" style=\"background-color:#007caa;\" >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1087703583\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:180px;\">\n\t\t\t<img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/Darnell-Hinton.webp\" class=\"attachment-original size-original\" alt=\"Darnell Hinton\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/Darnell-Hinton.webp 1000w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/Darnell-Hinton-300x200.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/Darnell-Hinton-768x512.webp 768w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/Darnell-Hinton-18x12.webp 18w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/Darnell-Hinton-510x340.webp 510w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1087703583 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p><strong>Darnell Hinton Jr.<\/strong><\/p>\n<p>Sales (USA)<\/p>\n<div class=\"social-icons follow-icons\" ><a href=\"mailto:support.us@imko.de\" data-label=\"E-mail\" target=\"_blank\" class=\"icon plain email tooltip\" title=\"Send us an email\" aria-label=\"Send us an email\" rel=\"nofollow noopener\" ><i class=\"icon-envelop\" ><\/i><\/a><a href=\"tel:+1 317 751 6578\" data-label=\"Phone\" target=\"_blank\" class=\"icon plain phone tooltip\" title=\"Call us\" aria-label=\"Call us\" rel=\"nofollow noopener\" ><i class=\"icon-phone\" ><\/i><\/a><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-462807687 > .col-inner {\n  padding: 0px 0px 25px 0px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row ma-col\"  id=\"row-749028293\">\n\n\n\t<div id=\"col-2043121594\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1 dark\" style=\"background-color:#007caa;\" >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1186539733\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:180px;\">\n\t\t\t<img decoding=\"async\" width=\"8192\" height=\"5464\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/farid-ahmadi_potrait.webp\" class=\"attachment-original size-original\" alt=\"Farid Ahmadi Potraitbild\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/farid-ahmadi_potrait.webp 8192w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/farid-ahmadi_potrait-300x200.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/farid-ahmadi_potrait-1024x683.webp 1024w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/farid-ahmadi_potrait-768x512.webp 768w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/farid-ahmadi_potrait-1536x1025.webp 1536w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/farid-ahmadi_potrait-18x12.webp 18w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/farid-ahmadi_potrait-510x340.webp 510w\" sizes=\"(max-width: 8192px) 100vw, 8192px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1186539733 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p><strong>Farid Ahmadi<\/strong><\/p>\n<p>Order processing | Export<\/p>\n<div class=\"social-icons follow-icons\" ><a href=\"mailto:sales@imko.de\" data-label=\"E-mail\" target=\"_blank\" class=\"icon plain email tooltip\" title=\"Send us an email\" aria-label=\"Send us an email\" rel=\"nofollow noopener\" ><i class=\"icon-envelop\" ><\/i><\/a><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2043121594 > .col-inner {\n  padding: 0px 0px 25px 0px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row ma-col\"  id=\"row-259207860\">\n\n\n\t<div id=\"col-16043247\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1 dark\" style=\"background-color:#007caa;\" >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_784690006\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:180px;\">\n\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/andreas-beetz_potrait-scaled.webp\" class=\"attachment-original size-original\" alt=\"Andread Beetz Potraitbild\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/andreas-beetz_potrait-scaled.webp 2560w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/andreas-beetz_potrait-300x200.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/andreas-beetz_potrait-1024x683.webp 1024w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/andreas-beetz_potrait-768x512.webp 768w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/andreas-beetz_potrait-1536x1024.webp 1536w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/andreas-beetz_potrait-2048x1366.webp 2048w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/andreas-beetz_potrait-18x12.webp 18w, https:\/\/www.imko.de\/wp-content\/uploads\/2025\/10\/andreas-beetz_potrait-510x340.webp 510w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_784690006 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p><strong>Andreas Beetz<\/strong><\/p>\n<p>Technology | Application<\/p>\n<div class=\"social-icons follow-icons\" ><a href=\"mailto:service@imko.de\" data-label=\"E-mail\" target=\"_blank\" class=\"icon plain email tooltip\" title=\"Send us an email\" aria-label=\"Send us an email\" rel=\"nofollow noopener\" ><i class=\"icon-envelop\" ><\/i><\/a><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-16043247 > .col-inner {\n  padding: 0px 0px 25px 0px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t\n<style>\n#slider-666567606 .flickity-slider > * {\n  max-width: 300px!important;\n}\n<\/style>\n<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2092435195 > .col-inner {\n  margin: 0px 0px -80px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2110605243 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_874004717\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1501616131\">\n\n\n\t<div id=\"col-1296025888\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row align-equal\"  id=\"row-882190157\">\n\n\n\t<div id=\"col-187734654\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3375244535\" class=\"text\">\n\t\t\n\n<h2>Figures - Data - Facts<\/h2>\n\t\t\n<style>\n#text-3375244535 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n<p>This section provides an overview of verified facts and information about our company. Here you will soon find important details about our services, quality standards and customer reviews. Stay tuned for trusted insights to help you make informed decisions.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-187734654 > .col-inner {\n  margin: 0px 0px -20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-266898211\" class=\"col cst-col-counter medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1\" style=\"background-color:rgba(153, 203, 221, 0.23);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1800190044\" class=\"text\">\n\t\t\n\n<h3 style=\"margin-bottom: 0px; font-family: 'Segoe UI', sans-serif;\"><span class=\"count-up\">153<\/span><\/h3>\n\t\t\n<style>\n#text-1800190044 {\n  font-size: 4rem;\n}\n@media (min-width:550px) {\n  #text-1800190044 {\n    font-size: 3rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2257233094\" class=\"text\">\n\t\t\n\n<p>Distribution countries<\/p>\n\t\t\n<style>\n#text-2257233094 {\n  font-size: 1.15rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-266898211 > .col-inner {\n  padding: 50px 25px 25px 25px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1293526382\" class=\"col cst-col-counter medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1\" style=\"background-color:rgba(153, 203, 221, 0.23);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-4004917596\" class=\"text\">\n\t\t\n\n<h3 style=\"margin-bottom: 0px; font-family: 'Segoe UI', sans-serif;\"><span class=\"count-up\">86<\/span><\/h3>\n\t\t\n<style>\n#text-4004917596 {\n  font-size: 4rem;\n}\n@media (min-width:550px) {\n  #text-4004917596 {\n    font-size: 3rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3404970056\" class=\"text\">\n\t\t\n\n<p>Sales partner<\/p>\n\t\t\n<style>\n#text-3404970056 {\n  font-size: 1.15rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1293526382 > .col-inner {\n  padding: 50px 25px 25px 25px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1160257339\" class=\"col cst-col-counter medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1\" style=\"background-color:rgba(153, 203, 221, 0.23);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1300760796\" class=\"text\">\n\t\t\n\n<h3 style=\"margin-bottom: 0px; font-family: 'Segoe UI', sans-serif;\"><span class=\"count-up\">198<\/span><\/h3>\n\t\t\n<style>\n#text-1300760796 {\n  font-size: 4rem;\n}\n@media (min-width:550px) {\n  #text-1300760796 {\n    font-size: 3rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3071727180\" class=\"text\">\n\t\t\n\n<p>Products<\/p>\n\t\t\n<style>\n#text-3071727180 {\n  font-size: 1.15rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1160257339 > .col-inner {\n  padding: 50px 25px 25px 25px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-370943485\" class=\"col cst-col-counter medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center box-shadow-1\" style=\"background-color:rgba(153, 203, 221, 0.23);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1288816611\" class=\"text\">\n\t\t\n\n<h3 style=\"margin-bottom: 0px; font-family: 'Segoe UI', sans-serif;\"><span class=\"count-up\">3<\/span><\/h3>\n\t\t\n<style>\n#text-1288816611 {\n  font-size: 4rem;\n}\n@media (min-width:550px) {\n  #text-1288816611 {\n    font-size: 3rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-709329089\" class=\"text\">\n\t\t\n\n<p>Worldwide service centres<\/p>\n\t\t\n<style>\n#text-709329089 {\n  font-size: 1.15rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-370943485 > .col-inner {\n  padding: 50px 25px 25px 25px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1296025888 > .col-inner {\n  margin: 0px 0px -50px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_874004717 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1963845466\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-785192531\">\n\n\n\t<div id=\"col-330597860\" class=\"col cst-col-height small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n<h2>Customer testimonials<\/h2>\n<p>Below you will find some of our references.<\/p>\n<div class=\"slider-wrapper relative\" id=\"slider-1381226089\" >\n    <div class=\"slider slider-nav-simple slider-nav-large slider-nav-dark slider-nav-outside slider-style-focus slider-show-nav\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 6000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": false,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"row\"  id=\"row-1090663629\">\n\n\n\t<div id=\"col-135355305\" class=\"col cst-bg-reviews small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-2 dark\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 30px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"color:rgb(255, 255, 255);\">\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1em\" height=\"1em\" viewbox=\"0 0 24 24\"><path fill=\"white\" d=\"M21.35 11.1h-9.17v2.73h6.51c-.33 3.81-3.5 5.44-6.5 5.44C8.36 19.27 5 16.25 5 12c0-4.1 3.2-7.27 7.2-7.27c3.09 0 4.9 1.97 4.9 1.97L19 4.72S16.56 2 12.1 2C6.42 2 2.03 6.8 2.03 12c0 5.05 4.13 10 10.22 10c5.35 0 9.25-3.67 9.25-9.09c0-1.15-.15-1.81-.15-1.81\"\/><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p><em>Our plant in Stuttgart works fully automatically with a total of eight SONO moisture probes. Thanks to the convincing moisture measurement, even of coarse aggregates, we can now also better comply with and control concrete recipes. We have checked the measured moisture values of the SONO probes in our laboratory and can confirm accuracies of 1-2 litres per m\u00b3. In both summer and winter operation, everything runs without recalibration.<\/em><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-135355305 > .col-inner {\n  padding: 25px 25px 25px 25px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-598866605\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"288\" height=\"168\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/holicim-logo.webp\" class=\"attachment-medium size-medium\" alt=\"holicim-logo\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p><span data-text-color=\"primary\"><strong>Werner Lehmann<br \/><\/strong><\/span>Technical Manager at HOLCIM GmbH in Stuttgart<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-4575928\">\n\n\n\t<div id=\"col-566204125\" class=\"col cst-bg-reviews small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-2 dark\" style=\"background-color:#9aca77;\" >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 30px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"color:rgb(255, 255, 255);\">\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1em\" height=\"1em\" viewbox=\"0 0 24 24\"><path fill=\"white\" d=\"M21.35 11.1h-9.17v2.73h6.51c-.33 3.81-3.5 5.44-6.5 5.44C8.36 19.27 5 16.25 5 12c0-4.1 3.2-7.27 7.2-7.27c3.09 0 4.9 1.97 4.9 1.97L19 4.72S16.56 2 12.1 2C6.42 2 2.03 6.8 2.03 12c0 5.05 4.13 10 10.22 10c5.35 0 9.25-3.67 9.25-9.09c0-1.15-.15-1.81-.15-1.81\"\/><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p><em>Our research includes investigations in rice and wheat fields in Nepal. Specifically, we evaluated different tillage and grain-specific measures on soil physics to assess subsequent plant growth. The measurement of soil moisture in different soil profiles is crucial for the assessment and interpretation of different plant growth. For this purpose, we have purchased a TRIME-T3 tube probe system. We have successfully used this system in both rice and wheat fields. The TRIME tube probe measurement system guaranteed us flexibility, repeatability and representativeness of the measurement results. The TRIME system is lightweight, exceptionally easy to use and quick to transport between the individual measuring points. Based on the positive experience, a colleague at our institute has ordered another TRIME system.<\/em><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-566204125 > .col-inner {\n  padding: 25px 25px 25px 25px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1093399341\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:1px;\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p><span data-text-color=\"primary\"><strong>Andrew McDonald<br \/><\/strong><\/span>Cornell University USA, Institute for Soil Science and Atmospheric Research<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1093399341 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1657319923\">\n\n\n\t<div id=\"col-2019523471\" class=\"col cst-bg-reviews small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-2 dark\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 30px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"color:rgb(255, 255, 255);\">\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1em\" height=\"1em\" viewbox=\"0 0 24 24\"><path fill=\"white\" d=\"M21.35 11.1h-9.17v2.73h6.51c-.33 3.81-3.5 5.44-6.5 5.44C8.36 19.27 5 16.25 5 12c0-4.1 3.2-7.27 7.2-7.27c3.09 0 4.9 1.97 4.9 1.97L19 4.72S16.56 2 12.1 2C6.42 2 2.03 6.8 2.03 12c0 5.05 4.13 10 10.22 10c5.35 0 9.25-3.67 9.25-9.09c0-1.15-.15-1.81-.15-1.81\"\/><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p><em>A value of EUR 1.92 per mixing process means EUR 19.20 with at least ten incorrect measurements per day. Multiplied by 200 production days, this amounts to EUR 3,840 per year. This alone, plus the savings on lime surcharges, fully compensates for the costs of converting to the SONO-Vario within the first year. I can recommend the SONO-Vario for moisture determination at any time.<\/em><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2019523471 > .col-inner {\n  padding: 25px 25px 25px 25px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1545668277\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:1px;\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p><span data-text-color=\"primary\"><strong>Ludger P\u00f6pping<br \/><\/strong><\/span>Cornell University USA, Institute for Soil Science and Atmospheric Research<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-942648753\">\n\n\n\t<div id=\"col-330421939\" class=\"col cst-bg-reviews small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-2 dark\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 30px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"color:rgb(255, 255, 255);\">\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1em\" height=\"1em\" viewbox=\"0 0 24 24\"><path fill=\"white\" d=\"M21.35 11.1h-9.17v2.73h6.51c-.33 3.81-3.5 5.44-6.5 5.44C8.36 19.27 5 16.25 5 12c0-4.1 3.2-7.27 7.2-7.27c3.09 0 4.9 1.97 4.9 1.97L19 4.72S16.56 2 12.1 2C6.42 2 2.03 6.8 2.03 12c0 5.05 4.13 10 10.22 10c5.35 0 9.25-3.67 9.25-9.09c0-1.15-.15-1.81-.15-1.81\"\/><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p><em>The Heidelberg Cement Group uses IMKO SONO sensors at many locations in Europe and Asia. The probes are typically installed under the dosing flaps in our ready-mix concrete mixing plants to measure the material moisture, especially of the fine aggregates. Heidelberg Cement considers the IMKO TDR technology to be the top solution for online measurement of aggregate moisture, as it provides very accurate results over a very long period of time without the need for recalibration due to wear of the probe head.<\/em><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-330421939 > .col-inner {\n  padding: 25px 25px 25px 25px;\n  border-radius: 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1687309027\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"color:rgb(255, 255, 255);\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p><span data-text-color=\"primary\"><strong>Dr. Jan Meinen<br \/><\/strong><\/span>Director CCR WSE | Heidelberger Cement<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t\n<style>\n#slider-1381226089 .flickity-slider > * {\n  max-width: 390px!important;\n}\n<\/style>\n<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1963845466 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-874727474\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-874727474 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-21","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcber uns - IMKO - Experten f\u00fcr Feuchtesensoren<\/title>\n<meta name=\"description\" content=\"Erfahren Sie mehr \u00fcber IMKO, den Spezialisten f\u00fcr Feuchtemesstechnik. Qualit\u00e4t und Innovation seit 1984. Jetzt entdecken!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.imko.de\/en\/about-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcber uns - IMKO - Experten f\u00fcr Feuchtesensoren\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie mehr \u00fcber IMKO, den Spezialisten f\u00fcr Feuchtemesstechnik. Qualit\u00e4t und Innovation seit 1984. Jetzt entdecken!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.imko.de\/en\/about-us\/\" \/>\n<meta property=\"og:site_name\" content=\"IMKO - Experten f\u00fcr Feuchtesensoren\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-19T16:27:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.imko.de\\\/ueber-uns\\\/\",\"url\":\"https:\\\/\\\/www.imko.de\\\/ueber-uns\\\/\",\"name\":\"\u00dcber uns - IMKO - Experten f\u00fcr Feuchtesensoren\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.imko.de\\\/#website\"},\"datePublished\":\"2024-07-16T18:40:10+00:00\",\"dateModified\":\"2025-10-19T16:27:55+00:00\",\"description\":\"Erfahren Sie mehr \u00fcber IMKO, den Spezialisten f\u00fcr Feuchtemesstechnik. Qualit\u00e4t und Innovation seit 1984. Jetzt entdecken!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.imko.de\\\/ueber-uns\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.imko.de\\\/ueber-uns\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.imko.de\\\/ueber-uns\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.imko.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcber uns\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.imko.de\\\/#website\",\"url\":\"https:\\\/\\\/www.imko.de\\\/\",\"name\":\"IMKO - Experten f\u00fcr Feuchtesensoren\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.imko.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcber uns - IMKO - Experten f\u00fcr Feuchtesensoren","description":"Erfahren Sie mehr \u00fcber IMKO, den Spezialisten f\u00fcr Feuchtemesstechnik. Qualit\u00e4t und Innovation seit 1984. Jetzt entdecken!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.imko.de\/en\/about-us\/","og_locale":"en_GB","og_type":"article","og_title":"\u00dcber uns - IMKO - Experten f\u00fcr Feuchtesensoren","og_description":"Erfahren Sie mehr \u00fcber IMKO, den Spezialisten f\u00fcr Feuchtemesstechnik. Qualit\u00e4t und Innovation seit 1984. Jetzt entdecken!","og_url":"https:\/\/www.imko.de\/en\/about-us\/","og_site_name":"IMKO - Experten f\u00fcr Feuchtesensoren","article_modified_time":"2025-10-19T16:27:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.imko.de\/ueber-uns\/","url":"https:\/\/www.imko.de\/ueber-uns\/","name":"\u00dcber uns - IMKO - Experten f\u00fcr Feuchtesensoren","isPartOf":{"@id":"https:\/\/www.imko.de\/#website"},"datePublished":"2024-07-16T18:40:10+00:00","dateModified":"2025-10-19T16:27:55+00:00","description":"Erfahren Sie mehr \u00fcber IMKO, den Spezialisten f\u00fcr Feuchtemesstechnik. Qualit\u00e4t und Innovation seit 1984. Jetzt entdecken!","breadcrumb":{"@id":"https:\/\/www.imko.de\/ueber-uns\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.imko.de\/ueber-uns\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.imko.de\/ueber-uns\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.imko.de\/"},{"@type":"ListItem","position":2,"name":"\u00dcber uns"}]},{"@type":"WebSite","@id":"https:\/\/www.imko.de\/#website","url":"https:\/\/www.imko.de\/","name":"IMKO - Experts for humidity sensors","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.imko.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/pages\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":80,"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/pages\/21\/revisions"}],"predecessor-version":[{"id":31802,"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/pages\/21\/revisions\/31802"}],"wp:attachment":[{"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/media?parent=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}