{"id":1991,"date":"2024-11-17T09:47:09","date_gmt":"2024-11-17T09:47:09","guid":{"rendered":"https:\/\/medien-portal.at\/?post_type=product&#038;p=1991"},"modified":"2025-03-19T16:18:35","modified_gmt":"2025-03-19T16:18:35","slug":"pico-32","status":"publish","type":"product","link":"https:\/\/www.imko.de\/en\/produkt\/pico-32\/","title":{"rendered":"PICO 32"},"content":{"rendered":"<div class=\"row\"  id=\"row-1489633517\">\n\n\t<div id=\"col-1913930096\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"tabbed-content\">\n\t\t\t\n\t\t\t<ul class=\"nav nav-tabs nav-normal nav-size-normal nav-left\" role=\"tablist\"><li id=\"tab-beschreibung\" class=\"tab active has-icon\" role=\"presentation\"><a href=\"#tab_beschreibung\" role=\"tab\" aria-selected=\"true\" aria-controls=\"tab_beschreibung\"><span>Product description<\/span><\/a><\/li>\n<li id=\"tab-anwendung\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_anwendung\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_anwendung\"><span>Application<\/span><\/a><\/li>\n<li id=\"tab-tech.-daten\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_tech.-daten\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_tech.-daten\"><span>tech. Data<\/span><\/a><\/li>\n<li id=\"tab-download\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_download\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_download\"><span>Download<\/span><\/a><\/li>\n<li id=\"tab-varianten\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_varianten\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_varianten\"><span>Variants<\/span><\/a><\/li>\n<li id=\"tab-einbau\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_einbau\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_einbau\"><span>Installation<\/span><\/a><\/li><\/ul><div class=\"tab-panels\"><div id=\"tab_beschreibung\" class=\"panel active entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-beschreibung\">\n<p>The soil moisture probe for high-resolution and selective measuring tasks.<\/p>\n<\/div>\n<div id=\"tab_anwendung\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-anwendung\">\n<p>Greenhouse &amp; high-resolution monitoring<\/p>\n<\/div>\n<div id=\"tab_tech.-daten\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-tech.-daten\">\n\n<table style=\"width: 100%; border-collapse: collapse; border: 1px solid #ccc;\">\n<tbody>\n<tr>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">Temperature range<\/td>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">-15\u00b0C &#8230; 50\u00b0C<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">Power supply<\/td>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">+7V to +24V DC<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">Special conditions<\/td>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">Optional probe rods in 50, 80, 100mm length<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">Signal output<\/td>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">2 x analogue output 0..1V<br \/>\nOutput 1: Humidity in %<br \/>\nOutput 2: Temperature<br \/>\nor optionally conductivity or standard deviation<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">Interfaces<\/td>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">RS485 or IMP bus<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">Sensor dimension<\/td>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">155 x 32 mm (length x diameter)<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">Weight<\/td>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">IP protection class<\/td>\n<td style=\"border: 1px solid #ccc; padding: 8px;\">IP68<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<\/div>\n<div id=\"tab_download\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-download\">\n<a href=\"https:\/\/www.imko.de\/wp-content\/uploads\/2025\/05\/Manual_TRIME_PICO32_64_V3.pdf\" target=\"_blank\" class=\"button primary is-outline lowercase\" rel=\"noopener\"  style=\"border-radius:5px;\">\n\t\t<span>Download datasheet<\/span>\n\t<\/a>\n\n<\/div>\n<div id=\"tab_varianten\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-varianten\">\n<p>Cable &amp; rod options<\/p>\n<\/div>\n<div id=\"tab_einbau\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-einbau\">\n<ul>\n<li>Mobile use<\/li>\n<li>Fixed installation in the floor<\/li>\n<li>Installation in the greenhouse<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1599324431\">\n\n\t<div id=\"col-1070368783\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>Accessories<\/h2>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1117461914\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"accordion\">\n\t<div id=\"accordion-615597027\" class=\"accordion-item\">\n\t\t<a id=\"accordion-615597027-label\" class=\"accordion-title plain\" href=\"#accordion-item-sm-usb\" aria-expanded=\"false\" aria-controls=\"accordion-615597027-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>SM-USB<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-615597027-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-615597027-label\" >\n\t\t\t\n<div class=\"row\"  id=\"row-583159737\">\n\n\t<div id=\"col-404814872\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>USB to RS485 and IMP bus converter module. For connecting SONO probes to a PC under Windows via the serial interface. For creating your own calibrations, test measurements with measurement data storage and other functions.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-937451639\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2141818792\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"600\" height=\"288\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/sm-usb.webp\" class=\"attachment-original size-original\" alt=\"sm-usb\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/sm-usb.webp 600w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/sm-usb-510x245.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/sm-usb-300x144.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/sm-usb-18x9.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2141818792 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1016300587\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1016300587-label\" class=\"accordion-title plain\" href=\"#accordion-item-hd2-mobiles-display\" aria-expanded=\"false\" aria-controls=\"accordion-1016300587-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Handheld Display HD2<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1016300587-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1016300587-label\" >\n\t\t\t\n<div class=\"row\"  id=\"row-579536149\">\n\n\t<div id=\"col-157432672\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Robust battery-operated mobile display unit for various probes:<br \/>\nSONO M1, -M1C, -M2.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1230441105\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1852991726\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"600\" height=\"288\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/hd2-mobiles-display.webp\" class=\"attachment-original size-original\" alt=\"hd2-mobiles-display\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/hd2-mobiles-display.webp 600w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/hd2-mobiles-display-510x245.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/hd2-mobiles-display-300x144.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/hd2-mobiles-display-18x9.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1852991726 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2021913854\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2021913854-label\" class=\"accordion-title plain\" href=\"#accordion-item-verl\u00e4ngerung\" aria-expanded=\"false\" aria-controls=\"accordion-2021913854-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Extension<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2021913854-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2021913854-label\" >\n\t\t\t\n<div class=\"row\"  id=\"row-102398036\">\n\n\t<div id=\"col-822158222\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>PICO 32\/64\/P2\/TRIME IT\/-ITC installation extension 0.5m incl. intermediate threaded piece. \u00d832mm<\/p>\n<p>PICO 32\/64\/P2\/TRIME IT\/-ITC installation extension 1.0m incl. intermediate threaded piece. \u00d832mm<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2089956484\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_464949106\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"600\" height=\"288\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/verlaengerung-32.webp\" class=\"attachment-original size-original\" alt=\"verl\u00e4ngerung-32\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/verlaengerung-32.webp 600w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/verlaengerung-32-510x245.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/verlaengerung-32-300x144.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/verlaengerung-32-18x9.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_464949106 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2597845262\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2597845262-label\" class=\"accordion-title plain\" href=\"#accordion-item-vorstechsonde-32mm\" aria-expanded=\"false\" aria-controls=\"accordion-2597845262-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Vorstechsonde 32mm<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2597845262-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2597845262-label\" >\n\t\t\t\n<div class=\"row\"  id=\"row-1550940370\">\n\n\t<div id=\"col-1743498364\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>For pre-drilling the floor before installing the probe. Rod length: 110mm<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1748048843\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1604584040\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"600\" height=\"288\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/vorstechsonde-32mm.webp\" class=\"attachment-original size-original\" alt=\"vorstechsonde-32mm\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/vorstechsonde-32mm.webp 600w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/vorstechsonde-32mm-510x245.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/vorstechsonde-32mm-300x144.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/vorstechsonde-32mm-18x9.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1604584040 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1412470584\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1412470584-label\" class=\"accordion-title plain\" href=\"#accordion-item-pico-bt\" aria-expanded=\"false\" aria-controls=\"accordion-1412470584-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>PICO-BT<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1412470584-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1412470584-label\" >\n\t\t\t\n<div class=\"row\"  id=\"row-2034293681\">\n\n\t<div id=\"col-598175183\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>For wireless transmission of soil moisture and soil temperature measurement data to an Android mobile device (version 2.2 or higher) running the Trime Blue app.<\/p>\n<p>Internal NiMh 2000mAh\/4.8V battery pack (sufficient for approx. 1500 measurements when fully charged)<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2138158504\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_49631068\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"600\" height=\"288\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/pico-bt.webp\" class=\"attachment-original size-original\" alt=\"pico-bt\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/pico-bt.webp 600w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/pico-bt-510x245.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/pico-bt-300x144.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/pico-bt-18x9.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_49631068 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2084846963\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2084846963-label\" class=\"accordion-title plain\" href=\"#accordion-item-c-box\" aria-expanded=\"false\" aria-controls=\"accordion-2084846963-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>C-Box<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2084846963-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2084846963-label\" >\n\t\t\t\n<div class=\"row\"  id=\"row-2124320645\">\n\n\t<div id=\"col-867000722\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Voltage \/ current transformer for PICO probes from 0..1V voltage level to current signal. 0....20mA (Option1) 4...20mA (Option2); cable lengths up to 100m possible; protection class IP65.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-606186321\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1757600115\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"600\" height=\"288\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/c-box-optional-accessories.webp\" class=\"attachment-original size-original\" alt=\"c-box-optional-accessories\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/c-box-optional-accessories.webp 600w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/c-box-optional-accessories-510x245.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/c-box-optional-accessories-300x144.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/c-box-optional-accessories-18x9.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1757600115 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3694544784\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3694544784-label\" class=\"accordion-title plain\" href=\"#accordion-item-e-box\" aria-expanded=\"false\" aria-controls=\"accordion-3694544784-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>E-Box<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3694544784-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3694544784-label\" >\n\t\t\t\n<div class=\"row\"  id=\"row-991951975\">\n\n\t<div id=\"col-1379393819\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Optional accessory for PICO 32\/64 for extending the PICO probe cable up to protection class IP65.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2097627354\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1807213763\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"600\" height=\"288\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/e-box-optional-accessories.webp\" class=\"attachment-original size-original\" alt=\"e-box-optional-accessories\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/e-box-optional-accessories.webp 600w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/e-box-optional-accessories-510x245.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/e-box-optional-accessories-300x144.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/e-box-optional-accessories-18x9.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1807213763 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3429964442\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3429964442-label\" class=\"accordion-title plain\" href=\"#accordion-item-logger-(cj-fragen)\" aria-expanded=\"false\" aria-controls=\"accordion-3429964442-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Logger (ask CJ)<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3429964442-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3429964442-label\" >\n\t\t\t\n<div class=\"row\"  id=\"row-904012802\">\n\n\t<div id=\"col-1337742852\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>On request<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-290696326\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1492157708\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"600\" height=\"288\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/logger-tinytag.webp\" class=\"attachment-original size-original\" alt=\"logger-tinytag\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/logger-tinytag.webp 600w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/logger-tinytag-510x245.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/logger-tinytag-300x144.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/logger-tinytag-18x9.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1492157708 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2487480795\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2487480795-label\" class=\"accordion-title plain\" href=\"#accordion-item-ersatz-st\u00e4be\" aria-expanded=\"false\" aria-controls=\"accordion-2487480795-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Spare rods<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2487480795-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2487480795-label\" >\n\t\t\t\n<div class=\"row\"  id=\"row-1554486950\">\n\n\t<div id=\"col-1840241450\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Spare rod PICO 32, 50mm, \u00f83.5mm<\/p>\n<p>Spare rod PICO 32, 80mm, \u00f83,5mm<\/p>\n<p>Spare rod PICO 32, 100mm, \u00f83,5mm<\/p>\n<p>Spare rod PICO 32, 110mm, \u00f83,5mm<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-297228240\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1943262325\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"600\" height=\"288\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/ersatzstab-pico-32.webp\" class=\"attachment-original size-original\" alt=\"ersatzstab-pico-32\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/ersatzstab-pico-32.webp 600w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/ersatzstab-pico-32-510x245.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/ersatzstab-pico-32-300x144.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/ersatzstab-pico-32-18x9.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1943262325 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2876690236\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2876690236-label\" class=\"accordion-title plain\" href=\"#accordion-item-kalibrier-set\" aria-expanded=\"false\" aria-controls=\"accordion-2876690236-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Calibration set<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2876690236-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2876690236-label\" >\n\t\t\t\n<div class=\"row\"  id=\"row-45479338\">\n\n\t<div id=\"col-1926974512\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>For basic calibration of TRIME PICO soil moisture probes.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-863418076\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1881354925\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"600\" height=\"288\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/Kalibrier-set.webp\" class=\"attachment-original size-original\" alt=\"Kalibrier-set\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/Kalibrier-set.webp 600w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/Kalibrier-set-510x245.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/Kalibrier-set-300x144.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/Kalibrier-set-18x9.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1881354925 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1689394673\">\n\n\t<div id=\"col-700108622\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"stack-444743044\" class=\"stack stack-row justify-between items-stretch sm:stack-col sm:justify-start sm:items-start\">\n\t\t\n\t<div id=\"text-2180579004\" class=\"text\">\n\t\t\n<h2>Alternative sensor<\/h2>\n\t\t\t<\/div>\n\t\n<a href=\"https:\/\/www.imko.de\/en\/contact\/\" class=\"button primary box-shadow-1\"  style=\"border-radius:5px;\">\n\t\t<span>Request now<\/span>\n\t<\/a>\n\n\t\t\n<style>\n#stack-444743044 > * {\n  --stack-gap: 1rem;\n}\n@media (min-width:550px) {\n  #stack-444743044 > * {\n    --stack-gap: 0rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-217872537\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/www.imko.de\/en\/product-2\/pico-64\/\" >\t\t\t<div class=\"\" >\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/PICO-64.webp\" class=\"attachment-original size-original\" alt=\"PICO 64\" srcset=\"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/PICO-64.webp 600w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/PICO-64-100x100.webp 100w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/PICO-64-510x510.webp 510w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/PICO-64-300x300.webp 300w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/PICO-64-150x150.webp 150w, https:\/\/www.imko.de\/wp-content\/uploads\/2024\/11\/PICO-64-12x12.webp 12w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\t<div id=\"text-4290247095\" class=\"text\">\n\t\t\n<h6><span style=\"color: #67717c;\">MOISTURE MEASUREMENT SOIL<\/span><\/h6>\n\t\t\n<style>\n#text-4290247095 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3004823684\" class=\"text\">\n\t\t\n<h5>PICO 64<\/h5>\n\t\t\n<style>\n#text-3004823684 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>The soil moisture probe for high-resolution and selective measuring tasks.<\/p>","protected":false},"featured_media":2294,"template":"","meta":[],"product_brand":[],"product_cat":[25],"product_tag":[],"class_list":{"0":"post-1991","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-feuchtemessung-boden","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PICO 32 - IMKO - Experten f\u00fcr Feuchtesensoren<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.imko.de\/en\/product-2\/pico-32\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PICO 32 - IMKO - Experten f\u00fcr Feuchtesensoren\" \/>\n<meta property=\"og:description\" content=\"Die Bodenfeuchtesonde f\u00fcr hochaufl\u00f6sende und punktuelle Messaufgaben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.imko.de\/en\/product-2\/pico-32\/\" \/>\n<meta property=\"og:site_name\" content=\"IMKO - Experten f\u00fcr Feuchtesensoren\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-19T16:18:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.imko.de\/wp-content\/uploads\/2025\/03\/ogimage-imko-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.imko.de\\\/produkt\\\/pico-32\\\/\",\"url\":\"https:\\\/\\\/www.imko.de\\\/produkt\\\/pico-32\\\/\",\"name\":\"PICO 32 - IMKO - Experten f\u00fcr Feuchtesensoren\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.imko.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.imko.de\\\/produkt\\\/pico-32\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.imko.de\\\/produkt\\\/pico-32\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.imko.de\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/pico-32-anwendung.webp\",\"datePublished\":\"2024-11-17T09:47:09+00:00\",\"dateModified\":\"2025-03-19T16:18:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.imko.de\\\/produkt\\\/pico-32\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.imko.de\\\/produkt\\\/pico-32\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.imko.de\\\/produkt\\\/pico-32\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.imko.de\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/pico-32-anwendung.webp\",\"contentUrl\":\"https:\\\/\\\/www.imko.de\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/pico-32-anwendung.webp\",\"width\":600,\"height\":600,\"caption\":\"pico-32-anwendung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.imko.de\\\/produkt\\\/pico-32\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.imko.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.imko.de\\\/?page_id=1968\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PICO 32\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.imko.de\\\/#website\",\"url\":\"https:\\\/\\\/www.imko.de\\\/\",\"name\":\"IMKO - Experten f\u00fcr Feuchtesensoren\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.imko.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PICO 32 - IMKO - Experten f\u00fcr Feuchtesensoren","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.imko.de\/en\/product-2\/pico-32\/","og_locale":"en_GB","og_type":"article","og_title":"PICO 32 - IMKO - Experten f\u00fcr Feuchtesensoren","og_description":"Die Bodenfeuchtesonde f\u00fcr hochaufl\u00f6sende und punktuelle Messaufgaben.","og_url":"https:\/\/www.imko.de\/en\/product-2\/pico-32\/","og_site_name":"IMKO - Experten f\u00fcr Feuchtesensoren","article_modified_time":"2025-03-19T16:18:35+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.imko.de\/wp-content\/uploads\/2025\/03\/ogimage-imko-logo.png","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.imko.de\/produkt\/pico-32\/","url":"https:\/\/www.imko.de\/produkt\/pico-32\/","name":"PICO 32 - IMKO - Experten f\u00fcr Feuchtesensoren","isPartOf":{"@id":"https:\/\/www.imko.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.imko.de\/produkt\/pico-32\/#primaryimage"},"image":{"@id":"https:\/\/www.imko.de\/produkt\/pico-32\/#primaryimage"},"thumbnailUrl":"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/12\/pico-32-anwendung.webp","datePublished":"2024-11-17T09:47:09+00:00","dateModified":"2025-03-19T16:18:35+00:00","breadcrumb":{"@id":"https:\/\/www.imko.de\/produkt\/pico-32\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.imko.de\/produkt\/pico-32\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.imko.de\/produkt\/pico-32\/#primaryimage","url":"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/12\/pico-32-anwendung.webp","contentUrl":"https:\/\/www.imko.de\/wp-content\/uploads\/2024\/12\/pico-32-anwendung.webp","width":600,"height":600,"caption":"pico-32-anwendung"},{"@type":"BreadcrumbList","@id":"https:\/\/www.imko.de\/produkt\/pico-32\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.imko.de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.imko.de\/?page_id=1968"},{"@type":"ListItem","position":3,"name":"PICO 32"}]},{"@type":"WebSite","@id":"https:\/\/www.imko.de\/#website","url":"https:\/\/www.imko.de\/","name":"IMKO - Experts for humidity sensors","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.imko.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/product\/1991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/media\/2294"}],"wp:attachment":[{"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/media?parent=1991"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/product_brand?post=1991"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/product_cat?post=1991"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/product_tag?post=1991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}