{"id":25,"count":4,"description":"","link":"https:\/\/www.imko.de\/en\/produkt-kategorie\/feuchtemessung-boden\/","name":"Moisture measurement soil","slug":"feuchtemessung-boden","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":2,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feuchtemessung Boden Archives - IMKO - Experten f\u00fcr Feuchtesensoren<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.imko.de\/en\/product-category\/feuchtemessung-boden\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feuchtemessung Boden Archives - IMKO - Experten f\u00fcr Feuchtesensoren\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.imko.de\/en\/product-category\/feuchtemessung-boden\/\" \/>\n<meta property=\"og:site_name\" content=\"IMKO - Experten f\u00fcr Feuchtesensoren\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.imko.de\\\/produkt-kategorie\\\/feuchtemessung-boden\\\/\",\"url\":\"https:\\\/\\\/www.imko.de\\\/produkt-kategorie\\\/feuchtemessung-boden\\\/\",\"name\":\"Feuchtemessung Boden Archives - IMKO - Experten f\u00fcr Feuchtesensoren\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.imko.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.imko.de\\\/produkt-kategorie\\\/feuchtemessung-boden\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.imko.de\\\/produkt-kategorie\\\/feuchtemessung-boden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.imko.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feuchtemessung Boden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.imko.de\\\/#website\",\"url\":\"https:\\\/\\\/www.imko.de\\\/\",\"name\":\"IMKO - Experten f\u00fcr Feuchtesensoren\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.imko.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feuchtemessung Boden Archives - IMKO - Experten f\u00fcr Feuchtesensoren","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.imko.de\/en\/product-category\/feuchtemessung-boden\/","og_locale":"en_GB","og_type":"article","og_title":"Feuchtemessung Boden Archives - IMKO - Experten f\u00fcr Feuchtesensoren","og_url":"https:\/\/www.imko.de\/en\/product-category\/feuchtemessung-boden\/","og_site_name":"IMKO - Experten f\u00fcr Feuchtesensoren","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.imko.de\/produkt-kategorie\/feuchtemessung-boden\/","url":"https:\/\/www.imko.de\/produkt-kategorie\/feuchtemessung-boden\/","name":"Feuchtemessung Boden Archives - IMKO - Experten f\u00fcr Feuchtesensoren","isPartOf":{"@id":"https:\/\/www.imko.de\/#website"},"breadcrumb":{"@id":"https:\/\/www.imko.de\/produkt-kategorie\/feuchtemessung-boden\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.imko.de\/produkt-kategorie\/feuchtemessung-boden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.imko.de\/"},{"@type":"ListItem","position":2,"name":"Feuchtemessung Boden"}]},{"@type":"WebSite","@id":"https:\/\/www.imko.de\/#website","url":"https:\/\/www.imko.de\/","name":"IMKO - Experts for humidity sensors","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.imko.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/product_cat\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.imko.de\/en\/wp-json\/wp\/v2\/product?product_cat=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}